{"id":4706,"date":"2025-06-26T13:46:13","date_gmt":"2025-06-26T11:46:13","guid":{"rendered":"https:\/\/plano-wfm.com\/at-de\/?p=4706"},"modified":"2026-04-15T11:22:29","modified_gmt":"2026-04-15T09:22:29","slug":"wir-sind-ilmenau","status":"publish","type":"post","link":"https:\/\/plano-wfm.com\/at-de\/wir-sind-ilmenau\/","title":{"rendered":"Wir sind Ilmenau"},"content":{"rendered":"<p>Ein starkes Zeichen f\u00fcr die Vielfalt, Kreativit\u00e4t und den Teamspirit unserer Stadt und wir bei plano solutions sind stolz darauf, ein Teil davon zu sein!<\/p>\n<p>#wirsindIlmenau ist eine Initiative der Stadt und der Technischen Universit\u00e4t, die den Fokus auf das legen, was Ilmenau im Kern ausmacht: die Menschen.<\/p>\n<p>Ob Alteingesessene oder Neuank\u00f6mmlinge, Studierende oder Unternehmen, Kulturschaffende oder Handwerker, die Kampagne zeigt die vielen Gesichter Ilmenaus und erz\u00e4hlt ihre Geschichten. Warum sie hier leben, was sie antreibt, was sie verbindet.<\/p>\n<p>Dabei wird eines klar: Ilmenau ist mehr als nur ein Ort \u2013 es ist ein Gef\u00fchl von Gemeinschaft, Offenheit und Zukunft.<\/p>\n<p>Als Ilmenauer Unternehmen war f\u00fcr uns sofort klar: Wir wollen dabei sein.<\/p>\n<p>Ilmenau hat viele Gesichter. Und eines davon ist: plano.<\/p>\n<p>Unser Herz schl\u00e4gt f\u00fcr Ilmenau \u2764\ufe0f Und genau von hier aus gestalten wir die Zukunft des Workforce Managements. Gemeinsam mit einem engagierten Team, f\u00fcr unsere Kunden, Partner und f\u00fcr unsere Stadt.<\/p>\n<p>Unser Video zur Kampagne #wirsindIlmenau gibt\u2019s auch auf unseren Social-Media-Kan\u00e4len zu sehen.<\/p>\n<p>&nbsp;<\/p>\n<div style=\"position: relative;padding-bottom: 56.25%;height: 0;overflow: hidden;max-width: 100%;margin: 0 auto;border-radius: 20px\"><iframe class=\"optanon-category-C0001\" style=\"position: absolute;top: 0;left: 0;width: 100%;height: 100%;border: 0\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/rPKfYAYIrnY?si=-9paak-2ttu1_pOo\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><br \/>\n<\/iframe><\/div>\n<p>Weitere Videos aus der Reihe &#8220;Wir sind Ilmenau&#8221; finden sich auf der Seite der <a href=\"https:\/\/www.ilmenau.de\/wirsindilmenau\" target=\"_blank\" rel=\"noopener\">Stadt Ilmenau<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein starkes Zeichen f\u00fcr die Vielfalt, Kreativit\u00e4t und den Teamspirit unserer Stadt und wir bei plano solutions sind stolz darauf, [&#8230;]<\/p>\n","protected":false},"author":227,"featured_media":4703,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-4706","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"jetpack_featured_media_url":"https:\/\/plano-wfm.com\/at-de\/wp-content\/uploads\/sites\/56\/2025\/06\/Header_News_WirsindIlmenau.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/plano-wfm.com\/at-de\/wp-json\/wp\/v2\/posts\/4706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plano-wfm.com\/at-de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plano-wfm.com\/at-de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plano-wfm.com\/at-de\/wp-json\/wp\/v2\/users\/227"}],"replies":[{"embeddable":true,"href":"https:\/\/plano-wfm.com\/at-de\/wp-json\/wp\/v2\/comments?post=4706"}],"version-history":[{"count":3,"href":"https:\/\/plano-wfm.com\/at-de\/wp-json\/wp\/v2\/posts\/4706\/revisions"}],"predecessor-version":[{"id":4777,"href":"https:\/\/plano-wfm.com\/at-de\/wp-json\/wp\/v2\/posts\/4706\/revisions\/4777"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plano-wfm.com\/at-de\/wp-json\/wp\/v2\/media\/4703"}],"wp:attachment":[{"href":"https:\/\/plano-wfm.com\/at-de\/wp-json\/wp\/v2\/media?parent=4706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plano-wfm.com\/at-de\/wp-json\/wp\/v2\/categories?post=4706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plano-wfm.com\/at-de\/wp-json\/wp\/v2\/tags?post=4706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}